{"id":15305,"date":"2026-05-12T16:00:38","date_gmt":"2026-05-12T14:00:38","guid":{"rendered":"https:\/\/ambbelgrado.esteri.it\/?p=15305"},"modified":"2026-05-12T16:01:27","modified_gmt":"2026-05-12T14:01:27","slug":"lambasciatore-ditalia-in-serbia-luca-gori-interviene-alla-conferenza-stampa-di-presentazione-della-partecipazione-italiana-alla-93a-fiera-internazionale-dellagricoltura-di","status":"publish","type":"post","link":"https:\/\/ambbelgrado.esteri.it\/it\/news\/dall_ambasciata\/2026\/05\/lambasciatore-ditalia-in-serbia-luca-gori-interviene-alla-conferenza-stampa-di-presentazione-della-partecipazione-italiana-alla-93a-fiera-internazionale-dellagricoltura-di\/","title":{"rendered":"L\u2019AMBASCIATORE D\u2019ITALIA IN SERBIA, LUCA GORI, INTERVIENE ALLA CONFERENZA STAMPA DI PRESENTAZIONE DELLA PARTECIPAZIONE ITALIANA ALLA 93\u00aa FIERA INTERNAZIONALE DELL\u2019AGRICOLTURA DI NOVI SAD"},"content":{"rendered":"<p>L\u2019Ambasciatore d\u2019Italia in Serbia, Luca Gori, \u00e8 intervenuto alla conferenza stampa \u2013 svoltasi presso Palazzo Italia a Belgrado &#8211; di presentazione della partecipazione italiana alla 93\u00aa edizione della Fiera Internazionale dell\u2019Agricoltura di Novi Sad, in programma dal 16 al 21 maggio 2026. L\u2019Italia si prepara ad una presenza collettiva di rilievo, con un padiglione dedicato di 400 metri quadri allestito dall\u2019Ufficio ICE di Belgrado, in collaborazione con la Federazione nazionale italiana dei costruttori di macchine per l&#8217;agricoltura \u2014 FederUnacoma.<\/p>\n<p>Oltre all\u2019Ambasciatore Gori, alla conferenza stampa sono intervenuti Antonio Ventresca, Direttore dell\u2019ufficio ICE di Belgrado, Slobodan Cvetkovi\u0107, Direttore della Fiera di Novi Sad, Jelena Nestorov Bizonj, Presidente dell\u2019Unione delle Cooperative della Vojvodina, e \u2014 tramite videomessaggio \u2014 Cristian Maretti, Presidente di Legacoop Agroalimentare.<\/p>\n<p>La partecipazione italiana alla Fiera di Novi Sad conferma il rafforzamento della cooperazione economica tra Italia e Serbia nel settore agroindustriale. Infatti, secondo i dati del 2025, l\u2019Italia \u00e8 diventata il secondo fornitore della Serbia nel comparto agroindustriale, con esportazioni pari a 100,2 milioni di euro, in crescita del 16% rispetto all\u2019anno precedente. Negli ultimi tre anni, l\u2019export italiano nel settore ha registrato un incremento complessivo del 54%.<\/p>\n<p>Nel corso della conferenza \u00e8 stato illustrato il ricco programma di attivit\u00e0 che accompagner\u00e0 la presenza italiana in fiera, articolato tra area espositiva, seminari tematici, workshop informativi, incontri istituzionali e sessioni B2B. Grazie alla rete regionale dell\u2019Agenzia ICE, circa 30 importatori e distributori provenienti da otto Paesi dei Balcani prenderanno parte alle attivit\u00e0 fieristiche, creando nuove opportunit\u00e0 di collaborazione commerciale con le imprese italiane e serbe.<\/p>\n<p>Tra gli appuntamenti principali figura poi la firma del Memorandum di Cooperazione tra Legacoop Agroalimentare e l\u2019Unione delle Cooperative della Vojvodina, prevista per il 19 maggio. L\u2019intesa punta a promuovere nuove forme di collaborazione tra il sistema cooperativo italiano e quello serbo, con particolare attenzione alla valorizzazione dell\u2019aggregazione dei produttori agricoli, all\u2019innovazione tecnologica, alla sostenibilit\u00e0 e alla digitalizzazione delle filiere.<\/p>\n<p>\u201cLa Fiera di Novi Sad si conferma ancora una volta una piattaforma strategica per attivare nuovi impulsi alla cooperazione economica tra Italia e Serbia nel settore agroindustriale\u201d, ha dichiarato il direttore dell\u2019ufficio ICE, Antonio Ventresca. \u201cIn questo contesto \u2013 ha soggiunto &#8211; si inserisce anche la firma del Memorandum tra Legacoop Agroalimentare e l\u2019Unione delle Cooperative della Vojvodina: il fatto che l\u2019Italia sia diventata il secondo fornitore della Serbia nel comparto agroindustriale conferma il rafforzamento di una partnership economica sempre pi\u00f9 dinamica e strutturata\u201d.<\/p>\n<p>\u201cIn un contesto internazionale in cui innovazione, sostenibilit\u00e0 e sicurezza alimentare assumono un\u2019importanza sempre maggiore, la cooperazione agroindustriale tra Italia e Serbia rappresenta un settore strategico ed in forte crescita\u201d, ha dichiarato l\u2019Ambasciatore d\u2019Italia in Serbia, Luca Gori. \u201cLa partecipazione italiana alla Fiera di Novi Sad \u2013 ha egli aggiunto \u2013 conferma la nostra volont\u00e0 di accompagnare il percorso di modernizzazione dell\u2019agricoltura serba attraverso tecnologie, competenze e partenariati di qualit\u00e0 con il nostro Paese\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"L\u2019Ambasciatore d\u2019Italia in Serbia, Luca Gori, \u00e8 intervenuto alla conferenza stampa \u2013 svoltasi presso Palazzo Italia a Belgrado &#8211; di presentazione della partecipazione italiana alla 93\u00aa edizione della Fiera Internazionale dell\u2019Agricoltura di Novi Sad, in programma dal 16 al 21 maggio 2026. L\u2019Italia si prepara ad una presenza collettiva di rilievo, con un padiglione dedicato [&hellip;]","protected":false},"author":7,"featured_media":15312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[8],"class_list":["post-15305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-diplomazia-economica"],"_links":{"self":[{"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/posts\/15305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=15305"}],"version-history":[{"count":1,"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/posts\/15305\/revisions"}],"predecessor-version":[{"id":15315,"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/posts\/15305\/revisions\/15315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/media\/15312"}],"wp:attachment":[{"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=15305"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambbelgrado.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=15305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}